{"id":286,"date":"2024-04-12T07:59:06","date_gmt":"2024-04-12T10:59:06","guid":{"rendered":"http:\/\/nova-pelle.local\/?page_id=286"},"modified":"2026-03-30T10:03:34","modified_gmt":"2026-03-30T13:03:34","slug":"convenio","status":"publish","type":"page","link":"https:\/\/novapelle.com.br\/novo\/convenio\/","title":{"rendered":"Conv\u00eanio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"286\" class=\"elementor elementor-286\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b61c98 e-flex e-con-boxed e-con e-parent\" data-id=\"5b61c98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5f9de6 elementor-widget elementor-widget-heading\" data-id=\"c5f9de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conv\u00eanios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ac985 elementor-widget elementor-widget-text-editor\" data-id=\"12ac985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Confira a lista com mais de 50 operadoras de sa\u00fade e empresas conveniadas \u00e0 Nova pelle.<\/p><p>\u00c9 importante salientar que nem a Nova Pelle, nem seus s\u00f3cios ou parceiros, est\u00e3o obrigados a prestar atendimento aos conv\u00eanios aqui listados sem pr\u00e9via confirma\u00e7\u00e3o, atrav\u00e9s de nossos canais de atendimento, e\/ou pr\u00e9via autoriza\u00e7\u00e3o das operadoras de sa\u00fade e empresas conveniadas. Em caso de d\u00favida, n\u00e3o deixe de nos procurar em nossos canais de atendimento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9514c7 elementor-widget elementor-widget-gallery\" data-id=\"a9514c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:6,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;16:9&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/AFEB-BRASAL.png\" data-width=\"200\" data-height=\"115\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/logo-anafe-ans-300x85.png\" data-width=\"300\" data-height=\"85\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/logo-planos-amil-300x132.png\" data-width=\"300\" data-height=\"132\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/assefaz_05_07_2022_12_52_53-300x225.jpg\" data-width=\"300\" data-height=\"225\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/medsculp-banco-central.jpg\" data-width=\"300\" data-height=\"211\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/bradesco-saude-logo-0-1-1536x1536-3-300x113.png\" data-width=\"300\" data-height=\"113\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/BRB.png\" data-width=\"286\" data-height=\"156\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/logo-caeme-300x146.jpg\" data-width=\"300\" data-height=\"146\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/cAESAN.png\" data-width=\"225\" data-height=\"225\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/cAREPLUS-300x164.jpg\" data-width=\"300\" data-height=\"164\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/Casembrapa-300x80.png\" data-width=\"300\" data-height=\"80\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/CASSI-1-300x124.jpg\" data-width=\"300\" data-height=\"124\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/unimed-central-nacional-logo-conteudo-300x174.png\" data-width=\"300\" data-height=\"174\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/CODEVASF-300x60.jpeg\" data-width=\"300\" data-height=\"60\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/CNTI.jpg\" data-width=\"300\" data-height=\"168\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/Logo-Conab-HorizontalZ-300x146.jpg\" data-width=\"300\" data-height=\"146\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/EMBRATEL-\u2013-DEMAIS-PLANOS-300x144.png\" data-width=\"300\" data-height=\"144\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/EMBRATEL-TELOS-300x84.jpg\" data-width=\"300\" data-height=\"84\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/FAPES-300x84.jpg\" data-width=\"300\" data-height=\"84\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/fascal-1-300x145.png\" data-width=\"300\" data-height=\"145\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/gravia_logo.jpg\" data-width=\"200\" data-height=\"200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/images-4-300x94.png\" data-width=\"300\" data-height=\"94\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/INFRAERO-300x144.png\" data-width=\"300\" data-height=\"144\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/iNTERLIFE-300x118.png\" data-width=\"300\" data-height=\"118\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/Life-Empresarial-1-300x146.png\" data-width=\"300\" data-height=\"146\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/Luminar-horizontal-cor-300x75.png\" data-width=\"300\" data-height=\"75\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/mEDISERVICE-300x150.png\" data-width=\"300\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/medsenior.png\" data-width=\"280\" data-height=\"97\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/plano-de-saude-notredame-300x103.png\" data-width=\"300\" data-height=\"103\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/oMINT-300x116.png\" data-width=\"300\" data-height=\"116\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/PETROBRAS-PETROLEO-300x101.png\" data-width=\"300\" data-height=\"101\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/PLAN-ASSISTE-MPU--300x90.png\" data-width=\"300\" data-height=\"90\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/POSTAL-SAUDE-300x177.png\" data-width=\"300\" data-height=\"177\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/PROASA.png\" data-width=\"225\" data-height=\"225\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/PRO-SAUDE-CAMARA-DOS-DEPUTADOS--300x145.png\" data-width=\"300\" data-height=\"145\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/REAL-GRANDEZA-300x117.webp\" data-width=\"300\" data-height=\"117\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/SAUDE-CAIXA-300x112.png\" data-width=\"300\" data-height=\"112\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/SERPRO-300x83.png\" data-width=\"300\" data-height=\"83\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/SIS-SENADO-300x175.jpg\" data-width=\"300\" data-height=\"175\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/STF-\u2013-MED-300x112.png\" data-width=\"300\" data-height=\"112\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/STJ-300x114.png\" data-width=\"300\" data-height=\"114\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/STM-300x169.jpg\" data-width=\"300\" data-height=\"169\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/TJDFT.png\" data-width=\"200\" data-height=\"200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/TRE.jpg\" data-width=\"273\" data-height=\"185\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/TRF-300x300.png\" data-width=\"300\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/TRT.png\" data-width=\"267\" data-height=\"189\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/TST-SAUDE-300x145.png\" data-width=\"300\" data-height=\"145\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/UNAFISCO.gif\" data-width=\"300\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/01\/logo-affego.png\" data-width=\"250\" data-height=\"157\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/06\/Seguros-Unimed-300x300.png\" data-width=\"300\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2025\/06\/Unimed-Central-Nacional-300x87.png\" data-width=\"300\" data-height=\"87\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/novapelle.com.br\/novo\/wp-content\/uploads\/2026\/03\/bombeiros-300x70.jpeg\" data-width=\"300\" data-height=\"70\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99d557b e-grid elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-con-boxed e-con e-child\" data-id=\"99d557b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8e6b7a elementor-widget elementor-widget-text-editor\" data-id=\"c8e6b7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>AFEB BRASAL<\/li>\n<li>AFFEGO<\/li>\n<li>AMIL<br><\/li><li>ANAFE SA\u00daDE (Associa\u00e7\u00e3o Nacional de Advogados P\u00fablicos Federais).<br><\/li>\n<li>ASETE<\/li>\n<li>ASSEFAZ<\/li>\n<li>BACEN<\/li>\n<li>BRADESCO<\/li>\n<li>BRB SAUDE<\/li>\n<li>CAEME-GO<\/li>\n<li>CAESAN<\/li>\n<li>CAMED<\/li>\n<li>CARE PLUS<\/li>\n<li>CASEMBRAPA<\/li>\n<li>CASSI<\/li>\n<li>CENTRAL NACIONAL UNIMED<\/li>\n<li>CNTI<\/li>\n<li>CODEVASF<\/li>\n<li>CONAB<\/li>\n<li>ELETRONORTE (E-VIDA)<\/li>\n<li>EMBRATEL DEMAIS PLAN<\/li>\n<li>FAPES (BNDES)<\/li>\n<li>FASCAL<\/li>\n<li>GAMA SAUDE<\/li>\n<li>GRAVIA<\/li>\n<li>INAS (GDF SAUDE)<\/li>\n<li>INFRAERO<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-966aa85 elementor-widget elementor-widget-text-editor\" data-id=\"966aa85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>LIFE EMPRESARIAL<\/li><li>MEDISERVICE<\/li><li>MEDSENIOR<\/li><li>NOTRE DAME<\/li><li>OMINT<\/li><li>SA\u00daDE PETROBRAS\u00a0<\/li><li>PLAN ASSISTE<\/li><li>PMDF<\/li><li>PF SA\u00daDE<\/li><li>POSTAL SA\u00daDE<\/li><li>PROASA<\/li><li>PR\u00d3 SA\u00daDE<\/li><li>REAL GRANDEZA<\/li><li>SAUDE CAIXA<\/li><li>SERPRO<\/li><li>SIS<\/li><li>STF \u2013 MED<\/li><li>STJ<\/li><li>STM<\/li><li>TJDFT<\/li><li>TRE<\/li><li>TRF \u2013 AMHPDF<\/li><li>TRT<\/li><li>TST SAUDE<\/li><li>UNAFISCO<\/li><li>INTERLIFE<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conv\u00eanios Confira a lista com mais de 50 operadoras de sa\u00fade e empresas conveniadas \u00e0 Nova pelle. \u00c9 importante salientar que nem a Nova Pelle, nem seus s\u00f3cios ou parceiros, est\u00e3o obrigados a prestar atendimento aos conv\u00eanios aqui listados sem pr\u00e9via confirma\u00e7\u00e3o, atrav\u00e9s de nossos canais de atendimento, e\/ou pr\u00e9via autoriza\u00e7\u00e3o das operadoras de sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"class_list":["post-286","page","type-page","status-publish","hentry"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conv\u00eanios Nova Pelle<\/title>\n<meta name=\"description\" content=\"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novapelle.com.br\/novo\/convenio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conv\u00eanios Nova Pelle\" \/>\n<meta property=\"og:description\" content=\"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novapelle.com.br\/novo\/convenio\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Pelle\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T13:03:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/convenio\\\/\",\"url\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/convenio\\\/\",\"name\":\"Conv\u00eanios Nova Pelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/#website\"},\"datePublished\":\"2024-04-12T10:59:06+00:00\",\"dateModified\":\"2026-03-30T13:03:34+00:00\",\"description\":\"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/convenio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/convenio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/convenio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conv\u00eanio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/#website\",\"url\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/\",\"name\":\"Nova Pelle\",\"description\":\"Dermatologia e Est\u00e9tica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/novapelle.com.br\\\/novo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conv\u00eanios Nova Pelle","description":"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novapelle.com.br\/novo\/convenio\/","og_locale":"pt_BR","og_type":"article","og_title":"Conv\u00eanios Nova Pelle","og_description":"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.","og_url":"https:\/\/novapelle.com.br\/novo\/convenio\/","og_site_name":"Nova Pelle","article_modified_time":"2026-03-30T13:03:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/novapelle.com.br\/novo\/convenio\/","url":"https:\/\/novapelle.com.br\/novo\/convenio\/","name":"Conv\u00eanios Nova Pelle","isPartOf":{"@id":"https:\/\/novapelle.com.br\/novo\/#website"},"datePublished":"2024-04-12T10:59:06+00:00","dateModified":"2026-03-30T13:03:34+00:00","description":"Atendimento via conv\u00eanios em Bras\u00edlia: mais de 50 operadoras conveniadas com Nova Pelle. Confirma\u00e7\u00e3o pr\u00e9via necess\u00e1ria.","breadcrumb":{"@id":"https:\/\/novapelle.com.br\/novo\/convenio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novapelle.com.br\/novo\/convenio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novapelle.com.br\/novo\/convenio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novapelle.com.br\/novo\/"},{"@type":"ListItem","position":2,"name":"Conv\u00eanio"}]},{"@type":"WebSite","@id":"https:\/\/novapelle.com.br\/novo\/#website","url":"https:\/\/novapelle.com.br\/novo\/","name":"Nova Pelle","description":"Dermatologia e Est\u00e9tica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novapelle.com.br\/novo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/pages\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":71,"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/pages\/286\/revisions"}],"predecessor-version":[{"id":2550,"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/pages\/286\/revisions\/2550"}],"wp:attachment":[{"href":"https:\/\/novapelle.com.br\/novo\/wp-json\/wp\/v2\/media?parent=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}